{"id":614,"count":1,"description":"","link":"https:\/\/www.hendrik.maekeler.eu\/se\/tag\/hamburger-beitrage-zur-numismatik\/","name":"Hamburger Beitr\u00e4ge zur Numismatik","slug":"hamburger-beitrage-zur-numismatik","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.hendrik.maekeler.eu\/se\/wp-json\/wp\/v2\/tags\/614"}],"collection":[{"href":"https:\/\/www.hendrik.maekeler.eu\/se\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.hendrik.maekeler.eu\/se\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.hendrik.maekeler.eu\/se\/wp-json\/wp\/v2\/posts?tags=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}